{"id":160,"date":"2017-01-02T18:39:47","date_gmt":"2017-01-02T21:39:47","guid":{"rendered":"http:\/\/eagle.com.br\/?p=160"},"modified":"2026-06-22T10:21:15","modified_gmt":"2026-06-22T13:21:15","slug":"dh69t","status":"publish","type":"post","link":"https:\/\/eagle.com.br\/en_us\/dh69t\/","title":{"rendered":"DH 69T"},"content":{"rendered":"<p><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:30px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-title title fusion-title-1 fusion-sep-none fusion-title-text fusion-title-size-three\" style=\"--awb-margin-top-small:0px;--awb-margin-right-small:0px;--awb-margin-bottom-small:20px;--awb-margin-left-small:0px;\"><h3 class=\"fusion-title-heading title-heading-left\" style=\"margin:0;\"><h1>DH 69T<\/h1><\/h3><\/div><div class=\"fusion-text fusion-text-1\"><p>Um dos viol\u00f5es com cordas de nylon mais vendidos da categoria recebe atualiza\u00e7\u00e3o! Ele acompanha equalizador Promix XR com afinador crom\u00e1tico digital e rastilho TruVibe para entregar sonoridade precisa e encorpada. O som ac\u00fastico aveludado e doce s\u00e3o caracter\u00edsticas marcantes. Seu desempenho em apresenta\u00e7\u00f5es ao vivo surpreende e o torna um \u00f3timo instrumento para estudo e apresenta\u00e7\u00f5es.<\/p>\n<\/div><div class=\"fusion-image-carousel fusion-image-carousel-auto fusion-image-carousel-1 fusion-no-medium-visibility fusion-no-large-visibility lightbox-enabled awb-image-carousel-top-below-caption\"><div class=\"awb-carousel awb-swiper awb-swiper-carousel awb-carousel--carousel awb-swiper-dots-position-bottom awb-imageframe-style awb-imageframe-style-below awb-imageframe-style-1\" data-layout=\"carousel\" data-autoplay=\"no\" data-autoplayspeed=\"5000\" data-autoplaypause=\"no\" data-loop=\"yes\" data-columns=\"1\" data-columnsmedium=\"1\" data-columnssmall=\"1\" data-itemmargin=\"13\" data-itemwidth=\"180\" data-touchscroll=\"no\" data-freemode=\"no\" data-imagesize=\"auto\" data-scrollitems=\"0\" data-centeredslides=\"no\" data-rotationangle=\"50\" data-depth=\"100\" data-speed=\"500\" data-shadow=\"no\" data-pagination=\"bullets\" style=\"--awb-columns:1;\"><div class=\"swiper-wrapper awb-image-carousel-wrapper fusion-flex-align-items-center\"><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><a data-rel=\"iLightbox[image_carousel_1]\" data-title=\"DH69T-VG-violao-classico-eletroacustico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-mobile\" aria-label=\"DH69T-VG-violao-classico-eletroacustico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-mobile\" href=\"https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-VG-violao-classico-eletroacustico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-mobile.jpg\" target=\"_self\"><img decoding=\"async\" width=\"748\" height=\"2000\" src=\"https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-VG-violao-classico-eletroacustico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-mobile.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-VG-violao-classico-eletroacustico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-mobile-112x300.jpg 112w, https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-VG-violao-classico-eletroacustico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-mobile-200x535.jpg 200w, https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-VG-violao-classico-eletroacustico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-mobile-383x1024.jpg 383w, https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-VG-violao-classico-eletroacustico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-mobile-400x1070.jpg 400w, https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-VG-violao-classico-eletroacustico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-mobile-574x1536.jpg 574w, https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-VG-violao-classico-eletroacustico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-mobile-600x1604.jpg 600w, https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-VG-violao-classico-eletroacustico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-mobile.jpg 748w\" sizes=\"(max-width: 748px) 100vw, 748px\" \/><\/a><\/div><div class=\"awb-imageframe-caption-container\"><div class=\"awb-imageframe-caption\"><h4 class=\"awb-imageframe-caption-title\">Vintage (VG)<\/h4><\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><a data-rel=\"iLightbox[image_carousel_1]\" data-title=\"DH69-NT-violao-classico-EAGLE-Pro-Series-DH69-NT-acabamento-natural-brilhante-mobile\" aria-label=\"DH69-NT-violao-classico-EAGLE-Pro-Series-DH69-NT-acabamento-natural-brilhante-mobile\" href=\"https:\/\/eagle.com.br\/wp-content\/uploads\/DH69-NT-violao-classico-EAGLE-Pro-Series-DH69-NT-acabamento-natural-brilhante-mobile.jpg\" target=\"_self\"><img decoding=\"async\" width=\"751\" height=\"2000\" src=\"https:\/\/eagle.com.br\/wp-content\/uploads\/DH69-NT-violao-classico-EAGLE-Pro-Series-DH69-NT-acabamento-natural-brilhante-mobile.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/eagle.com.br\/wp-content\/uploads\/DH69-NT-violao-classico-EAGLE-Pro-Series-DH69-NT-acabamento-natural-brilhante-mobile-113x300.jpg 113w, https:\/\/eagle.com.br\/wp-content\/uploads\/DH69-NT-violao-classico-EAGLE-Pro-Series-DH69-NT-acabamento-natural-brilhante-mobile-200x533.jpg 200w, https:\/\/eagle.com.br\/wp-content\/uploads\/DH69-NT-violao-classico-EAGLE-Pro-Series-DH69-NT-acabamento-natural-brilhante-mobile-385x1024.jpg 385w, https:\/\/eagle.com.br\/wp-content\/uploads\/DH69-NT-violao-classico-EAGLE-Pro-Series-DH69-NT-acabamento-natural-brilhante-mobile-400x1065.jpg 400w, https:\/\/eagle.com.br\/wp-content\/uploads\/DH69-NT-violao-classico-EAGLE-Pro-Series-DH69-NT-acabamento-natural-brilhante-mobile-577x1536.jpg 577w, https:\/\/eagle.com.br\/wp-content\/uploads\/DH69-NT-violao-classico-EAGLE-Pro-Series-DH69-NT-acabamento-natural-brilhante-mobile-600x1598.jpg 600w, https:\/\/eagle.com.br\/wp-content\/uploads\/DH69-NT-violao-classico-EAGLE-Pro-Series-DH69-NT-acabamento-natural-brilhante-mobile.jpg 751w\" sizes=\"(max-width: 751px) 100vw, 751px\" \/><\/a><\/div><div class=\"awb-imageframe-caption-container\"><div class=\"awb-imageframe-caption\"><h4 class=\"awb-imageframe-caption-title\">Natural (NT)<\/h4><\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><a data-rel=\"iLightbox[image_carousel_1]\" data-title=\"bag-deluxe-mobile\" aria-label=\"bag-deluxe-mobile\" href=\"https:\/\/eagle.com.br\/wp-content\/uploads\/bag-deluxe-mobile.jpg\" target=\"_self\"><img decoding=\"async\" width=\"800\" height=\"1958\" src=\"https:\/\/eagle.com.br\/wp-content\/uploads\/bag-deluxe-mobile.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/eagle.com.br\/wp-content\/uploads\/bag-deluxe-mobile-123x300.jpg 123w, https:\/\/eagle.com.br\/wp-content\/uploads\/bag-deluxe-mobile-200x490.jpg 200w, https:\/\/eagle.com.br\/wp-content\/uploads\/bag-deluxe-mobile-400x979.jpg 400w, https:\/\/eagle.com.br\/wp-content\/uploads\/bag-deluxe-mobile-418x1024.jpg 418w, https:\/\/eagle.com.br\/wp-content\/uploads\/bag-deluxe-mobile-600x1469.jpg 600w, https:\/\/eagle.com.br\/wp-content\/uploads\/bag-deluxe-mobile-628x1536.jpg 628w, https:\/\/eagle.com.br\/wp-content\/uploads\/bag-deluxe-mobile-768x1880.jpg 768w, https:\/\/eagle.com.br\/wp-content\/uploads\/bag-deluxe-mobile.jpg 800w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/div><div class=\"awb-imageframe-caption-container\"><div class=\"awb-imageframe-caption\"><h4 class=\"awb-imageframe-caption-title\">Bag Deluxe EAGLE<\/h4><\/div><\/div><\/div><\/div><\/div><div class=\"awb-swiper-button awb-swiper-button-prev\"><i class=\"awb-icon-angle-left\" aria-hidden=\"true\"><\/i><\/div><div class=\"awb-swiper-button awb-swiper-button-next\"><i class=\"awb-icon-angle-right\" aria-hidden=\"true\"><\/i><\/div><\/div><\/div><div class=\"fusion-image-carousel fusion-image-carousel-auto fusion-image-carousel-2 fusion-no-small-visibility lightbox-enabled awb-image-carousel-top-below-caption\"><div class=\"awb-carousel awb-swiper awb-swiper-carousel awb-carousel--carousel awb-swiper-dots-position-bottom awb-imageframe-style awb-imageframe-style-below awb-imageframe-style-2\" data-layout=\"carousel\" data-autoplay=\"no\" data-autoplayspeed=\"5000\" data-autoplaypause=\"no\" data-loop=\"yes\" data-columns=\"1\" data-columnsmedium=\"1\" data-columnssmall=\"1\" data-itemmargin=\"13\" data-itemwidth=\"180\" data-touchscroll=\"no\" data-freemode=\"no\" data-imagesize=\"auto\" data-scrollitems=\"0\" data-centeredslides=\"no\" data-rotationangle=\"50\" data-depth=\"100\" data-speed=\"500\" data-shadow=\"no\" data-pagination=\"bullets\" style=\"--awb-columns:1;\"><div class=\"swiper-wrapper awb-image-carousel-wrapper fusion-flex-align-items-center\"><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><a data-rel=\"iLightbox[image_carousel_2]\" data-title=\"DH69T-VG-violao-classico-eletroacustico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante\" aria-label=\"DH69T-VG-violao-classico-eletroacustico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante\" href=\"https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-VG-violao-classico-eletroacustico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante.jpg\" target=\"_self\"><img decoding=\"async\" width=\"2300\" height=\"860\" src=\"https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-VG-violao-classico-eletroacustico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-VG-violao-classico-eletroacustico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-200x75.jpg 200w, https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-VG-violao-classico-eletroacustico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-300x112.jpg 300w, https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-VG-violao-classico-eletroacustico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-400x150.jpg 400w, https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-VG-violao-classico-eletroacustico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-600x224.jpg 600w, https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-VG-violao-classico-eletroacustico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-768x287.jpg 768w, https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-VG-violao-classico-eletroacustico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-800x299.jpg 800w, https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-VG-violao-classico-eletroacustico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-1024x383.jpg 1024w, https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-VG-violao-classico-eletroacustico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-1200x449.jpg 1200w, https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-VG-violao-classico-eletroacustico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-1536x574.jpg 1536w, https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-VG-violao-classico-eletroacustico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante.jpg 2300w\" sizes=\"(max-width: 2300px) 100vw, 2300px\" \/><\/a><\/div><div class=\"awb-imageframe-caption-container\"><div class=\"awb-imageframe-caption\"><h2 class=\"awb-imageframe-caption-title\">Vintage (VG)<\/h2><\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><a data-rel=\"iLightbox[image_carousel_2]\" data-title=\"DH69-NT-violao-classico-EAGLE-Pro-Series-DH69-NT-acabamento-natural-brilhante\" aria-label=\"DH69-NT-violao-classico-EAGLE-Pro-Series-DH69-NT-acabamento-natural-brilhante\" href=\"https:\/\/eagle.com.br\/wp-content\/uploads\/DH69-NT-violao-classico-EAGLE-Pro-Series-DH69-NT-acabamento-natural-brilhante.jpg\" target=\"_self\"><img decoding=\"async\" width=\"2300\" height=\"864\" src=\"https:\/\/eagle.com.br\/wp-content\/uploads\/DH69-NT-violao-classico-EAGLE-Pro-Series-DH69-NT-acabamento-natural-brilhante.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/eagle.com.br\/wp-content\/uploads\/DH69-NT-violao-classico-EAGLE-Pro-Series-DH69-NT-acabamento-natural-brilhante-200x75.jpg 200w, https:\/\/eagle.com.br\/wp-content\/uploads\/DH69-NT-violao-classico-EAGLE-Pro-Series-DH69-NT-acabamento-natural-brilhante-300x113.jpg 300w, https:\/\/eagle.com.br\/wp-content\/uploads\/DH69-NT-violao-classico-EAGLE-Pro-Series-DH69-NT-acabamento-natural-brilhante-400x150.jpg 400w, https:\/\/eagle.com.br\/wp-content\/uploads\/DH69-NT-violao-classico-EAGLE-Pro-Series-DH69-NT-acabamento-natural-brilhante-600x225.jpg 600w, https:\/\/eagle.com.br\/wp-content\/uploads\/DH69-NT-violao-classico-EAGLE-Pro-Series-DH69-NT-acabamento-natural-brilhante-768x289.jpg 768w, https:\/\/eagle.com.br\/wp-content\/uploads\/DH69-NT-violao-classico-EAGLE-Pro-Series-DH69-NT-acabamento-natural-brilhante-800x301.jpg 800w, https:\/\/eagle.com.br\/wp-content\/uploads\/DH69-NT-violao-classico-EAGLE-Pro-Series-DH69-NT-acabamento-natural-brilhante-1024x385.jpg 1024w, https:\/\/eagle.com.br\/wp-content\/uploads\/DH69-NT-violao-classico-EAGLE-Pro-Series-DH69-NT-acabamento-natural-brilhante-1200x451.jpg 1200w, https:\/\/eagle.com.br\/wp-content\/uploads\/DH69-NT-violao-classico-EAGLE-Pro-Series-DH69-NT-acabamento-natural-brilhante-1536x577.jpg 1536w, https:\/\/eagle.com.br\/wp-content\/uploads\/DH69-NT-violao-classico-EAGLE-Pro-Series-DH69-NT-acabamento-natural-brilhante.jpg 2300w\" sizes=\"(max-width: 2300px) 100vw, 2300px\" \/><\/a><\/div><div class=\"awb-imageframe-caption-container\"><div class=\"awb-imageframe-caption\"><h2 class=\"awb-imageframe-caption-title\">Natural (NT)<\/h2><\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><a data-rel=\"iLightbox[image_carousel_2]\" data-title=\"bag-deluxe\" aria-label=\"bag-deluxe\" href=\"https:\/\/eagle.com.br\/wp-content\/uploads\/bag-deluxe.jpg\" target=\"_self\"><img decoding=\"async\" width=\"2000\" height=\"817\" src=\"https:\/\/eagle.com.br\/wp-content\/uploads\/bag-deluxe.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/eagle.com.br\/wp-content\/uploads\/bag-deluxe-200x82.jpg 200w, https:\/\/eagle.com.br\/wp-content\/uploads\/bag-deluxe-300x123.jpg 300w, https:\/\/eagle.com.br\/wp-content\/uploads\/bag-deluxe-400x163.jpg 400w, https:\/\/eagle.com.br\/wp-content\/uploads\/bag-deluxe-600x245.jpg 600w, https:\/\/eagle.com.br\/wp-content\/uploads\/bag-deluxe-669x272.jpg 669w, https:\/\/eagle.com.br\/wp-content\/uploads\/bag-deluxe-768x314.jpg 768w, https:\/\/eagle.com.br\/wp-content\/uploads\/bag-deluxe-800x327.jpg 800w, https:\/\/eagle.com.br\/wp-content\/uploads\/bag-deluxe-1024x418.jpg 1024w, https:\/\/eagle.com.br\/wp-content\/uploads\/bag-deluxe-1200x490.jpg 1200w, https:\/\/eagle.com.br\/wp-content\/uploads\/bag-deluxe-1536x627.jpg 1536w, https:\/\/eagle.com.br\/wp-content\/uploads\/bag-deluxe.jpg 2000w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/a><\/div><div class=\"awb-imageframe-caption-container\"><div class=\"awb-imageframe-caption\"><h2 class=\"awb-imageframe-caption-title\">Bag Deluxe EAGLE<\/h2><\/div><\/div><\/div><\/div><\/div><div class=\"awb-swiper-button awb-swiper-button-prev\"><i class=\"awb-icon-angle-left\" aria-hidden=\"true\"><\/i><\/div><div class=\"awb-swiper-button awb-swiper-button-next\"><i class=\"awb-icon-angle-right\" aria-hidden=\"true\"><\/i><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-background-color:#000000;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1144px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-padding-top:30px;--awb-padding-bottom:30px;--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"awb-gallery-wrapper awb-gallery-wrapper-1 button-span-no\"><div style=\"margin:-5px;--awb-bordersize:0px;\" class=\"fusion-gallery fusion-gallery-container fusion-grid-4 fusion-columns-total-8 fusion-gallery-layout-grid fusion-gallery-1\"><div style=\"padding:5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-4 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-NT-violao-classico-EAGLE-Pro-Series-DH69T-NT-acabamento-natural-brilhante-detalhe3.jpg\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-NT-violao-classico-EAGLE-Pro-Series-DH69T-NT-acabamento-natural-brilhante-detalhe3-320x202.jpg\" width=\"320\" height=\"202\" alt=\"\" title=\"DH69T-NT-violao-classico-EAGLE-Pro-Series-DH69T-NT-acabamento-natural-brilhante-detalhe3\" aria-label=\"DH69T-NT-violao-classico-EAGLE-Pro-Series-DH69T-NT-acabamento-natural-brilhante-detalhe3\" class=\"img-responsive wp-image-27006 fusion-gallery-image-size-fixed\" srcset=\"https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-NT-violao-classico-EAGLE-Pro-Series-DH69T-NT-acabamento-natural-brilhante-detalhe3-320x202.jpg 320w, https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-NT-violao-classico-EAGLE-Pro-Series-DH69T-NT-acabamento-natural-brilhante-detalhe3-700x441.jpg 700w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/><\/a><\/div><\/div><div style=\"padding:5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-4 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-NT-violao-classico-EAGLE-Pro-Series-DH69T-NT-acabamento-natural-brilhante-detalhe6.jpg\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-NT-violao-classico-EAGLE-Pro-Series-DH69T-NT-acabamento-natural-brilhante-detalhe6-320x202.jpg\" width=\"320\" height=\"202\" alt=\"\" title=\"DH69T-NT-violao-classico-EAGLE-Pro-Series-DH69T-NT-acabamento-natural-brilhante-detalhe6\" aria-label=\"DH69T-NT-violao-classico-EAGLE-Pro-Series-DH69T-NT-acabamento-natural-brilhante-detalhe6\" class=\"img-responsive wp-image-26998 fusion-gallery-image-size-fixed\" srcset=\"https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-NT-violao-classico-EAGLE-Pro-Series-DH69T-NT-acabamento-natural-brilhante-detalhe6-320x202.jpg 320w, https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-NT-violao-classico-EAGLE-Pro-Series-DH69T-NT-acabamento-natural-brilhante-detalhe6-700x441.jpg 700w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/><\/a><\/div><\/div><div style=\"padding:5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-4 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-NT-violao-classico-EAGLE-Pro-Series-DH69T-NT-acabamento-natural-brilhante-detalhe9.jpg\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-NT-violao-classico-EAGLE-Pro-Series-DH69T-NT-acabamento-natural-brilhante-detalhe9-320x202.jpg\" width=\"320\" height=\"202\" alt=\"\" title=\"DH69T-NT-violao-classico-EAGLE-Pro-Series-DH69T-NT-acabamento-natural-brilhante-detalhe9\" aria-label=\"DH69T-NT-violao-classico-EAGLE-Pro-Series-DH69T-NT-acabamento-natural-brilhante-detalhe9\" class=\"img-responsive wp-image-26999 fusion-gallery-image-size-fixed\" srcset=\"https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-NT-violao-classico-EAGLE-Pro-Series-DH69T-NT-acabamento-natural-brilhante-detalhe9-320x202.jpg 320w, https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-NT-violao-classico-EAGLE-Pro-Series-DH69T-NT-acabamento-natural-brilhante-detalhe9-700x441.jpg 700w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/><\/a><\/div><\/div><div style=\"padding:5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-4 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-VG-violao-classico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-detalhe2.jpg\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-VG-violao-classico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-detalhe2-320x202.jpg\" width=\"320\" height=\"202\" alt=\"\" title=\"DH69T-VG-violao-classico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-detalhe2\" aria-label=\"DH69T-VG-violao-classico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-detalhe2\" class=\"img-responsive wp-image-27000 fusion-gallery-image-size-fixed\" srcset=\"https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-VG-violao-classico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-detalhe2-320x202.jpg 320w, https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-VG-violao-classico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-detalhe2-700x441.jpg 700w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/><\/a><\/div><\/div><div class=\"clearfix\"><\/div><div style=\"padding:5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-4 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-VG-violao-classico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-detalhe5.1.jpg\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-VG-violao-classico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-detalhe5.1-320x202.jpg\" width=\"320\" height=\"202\" alt=\"\" title=\"DH69T-VG-violao-classico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-detalhe5.1\" aria-label=\"DH69T-VG-violao-classico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-detalhe5.1\" class=\"img-responsive wp-image-27001 fusion-gallery-image-size-fixed\" srcset=\"https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-VG-violao-classico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-detalhe5.1-320x202.jpg 320w, https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-VG-violao-classico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-detalhe5.1-700x441.jpg 700w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/><\/a><\/div><\/div><div style=\"padding:5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-4 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-VG-violao-classico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-detalhe4.jpg\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-VG-violao-classico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-detalhe4-320x202.jpg\" width=\"320\" height=\"202\" alt=\"\" title=\"DH69T-VG-violao-classico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-detalhe4\" aria-label=\"DH69T-VG-violao-classico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-detalhe4\" class=\"img-responsive wp-image-27002 fusion-gallery-image-size-fixed\" srcset=\"https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-VG-violao-classico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-detalhe4-320x202.jpg 320w, https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-VG-violao-classico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-detalhe4-700x441.jpg 700w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/><\/a><\/div><\/div><div style=\"padding:5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-4 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-VG-violao-classico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-detalhe6.jpg\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-VG-violao-classico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-detalhe6-320x202.jpg\" width=\"320\" height=\"202\" alt=\"\" title=\"DH69T-VG-violao-classico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-detalhe6\" aria-label=\"DH69T-VG-violao-classico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-detalhe6\" class=\"img-responsive wp-image-27003 fusion-gallery-image-size-fixed\" srcset=\"https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-VG-violao-classico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-detalhe6-320x202.jpg 320w, https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-VG-violao-classico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-detalhe6-700x441.jpg 700w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/><\/a><\/div><\/div><div style=\"padding:5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-4 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-VG-violao-classico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-detalhe12.jpg\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-VG-violao-classico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-detalhe12-320x202.jpg\" width=\"320\" height=\"202\" alt=\"\" title=\"DH69T-VG-violao-classico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-detalhe12\" aria-label=\"DH69T-VG-violao-classico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-detalhe12\" class=\"img-responsive wp-image-27005 fusion-gallery-image-size-fixed\" srcset=\"https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-VG-violao-classico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-detalhe12-320x202.jpg 320w, https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-VG-violao-classico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-detalhe12-700x441.jpg 700w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/><\/a><\/div><\/div><div class=\"clearfix\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-3 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--link_hover_color: var(--awb-color5);--link_color: var(--awb-color5);--awb-background-position:center bottom;--awb-border-sizes-top:0px;--awb-border-sizes-bottom:0px;--awb-border-sizes-left:0px;--awb-border-sizes-right:0px;--awb-border-color:var(--awb-color3);--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:100px;--awb-padding-right:30px;--awb-padding-bottom:100px;--awb-padding-left:30px;--awb-padding-top-medium:72px;--awb-padding-bottom-medium:72px;--awb-padding-top-small:48px;--awb-padding-bottom-small:48px;--awb-padding-left-small:30px;--awb-margin-top:0px;--awb-margin-bottom:0px;--awb-background-color:#ededed;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-stretch fusion-flex-content-wrap\" style=\"max-width:1144px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_1_2 1_2 fusion-flex-column fusion-animated\" style=\"--awb-bg-position:center center;--awb-bg-blend:multiply;--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:13.44%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:3.84%;--awb-width-medium:40%;--awb-order-medium:0;--awb-spacing-right-medium:9.6%;--awb-spacing-left-medium:4.8%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-margin-bottom-small:40px;--awb-spacing-left-small:1.92%;\" data-animationType=\"fadeInRight\" data-animationDuration=\"1.3\" data-animationOffset=\"top-into-view\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-center fusion-content-layout-column\"><div class=\"fusion-image-element\" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-overlay-color:var(--awb-color1);--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-1 hover-type-none has-aspect-ratio\"><img decoding=\"async\" width=\"1200\" height=\"1200\" alt=\"lateral do viol\u00e3o nylon DH 69, DH 69T, roseta de viol\u00e3o\" title=\"DH69T-VG-violao-classico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-detalhe2\" src=\"https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-VG-violao-classico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-detalhe2-1.jpg\" class=\"img-responsive wp-image-27011 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" srcset=\"https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-VG-violao-classico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-detalhe2-1-200x200.jpg 200w, https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-VG-violao-classico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-detalhe2-1-400x400.jpg 400w, https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-VG-violao-classico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-detalhe2-1-600x600.jpg 600w, https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-VG-violao-classico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-detalhe2-1-800x800.jpg 800w, https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-VG-violao-classico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-detalhe2-1.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, (max-width: 640px) 100vw, 600px\" \/><\/span><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-3 fusion_builder_column_1_2 1_2 fusion-flex-column fusion-animated\" style=\"--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:3.84%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:3.84%;--awb-width-medium:60%;--awb-order-medium:0;--awb-margin-top-medium:2vw;--awb-spacing-right-medium:3.2%;--awb-margin-bottom-medium:2vw;--awb-spacing-left-medium:3.2%;--awb-width-small:100%;--awb-order-small:1;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-animationType=\"fadeInLeft\" data-animationDuration=\"1.3\" data-animationOffset=\"top-into-view\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-center fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-2 fusion-sep-none fusion-title-text fusion-title-size-one fusion-animated\" style=\"--awb-text-color:#000000;--awb-margin-top:10px;--awb-margin-bottom:30px;--awb-margin-top-small:10px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;--awb-sep-color:var(--awb-color3);\" data-animationType=\"fadeInRight\" data-animationDuration=\"1.2\" data-animationOffset=\"top-into-view\"><h1 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:48;line-height:1.4;\">Marcante e preciso.<\/h1><\/div><div class=\"fusion-text fusion-text-2 fusion-text-no-margin\" style=\"--awb-font-size:22px;--awb-line-height:var(--awb-typography4-line-height);--awb-letter-spacing:var(--awb-typography4-letter-spacing);--awb-text-transform:var(--awb-typography4-text-transform);--awb-text-color:#000000;--awb-margin-right:15%;--awb-margin-bottom:45px;\"><p>Fabricado com madeiras selecionadas, acabamento cuidadoso e excelente tocabilidade, o DH 69T entrega uma sonoridade equilibrada, com \u00f3tima resposta nos m\u00e9dios e nos graves, al\u00e9m de proje\u00e7\u00e3o e defini\u00e7\u00e3o na medida certa para tocar sozinho, em grupo ou no palco.<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-4 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--link_hover_color: var(--awb-color5);--link_color: var(--awb-color5);--awb-background-position:center bottom;--awb-border-sizes-top:0px;--awb-border-sizes-bottom:0px;--awb-border-sizes-left:0px;--awb-border-sizes-right:0px;--awb-border-color:var(--awb-color3);--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:100px;--awb-padding-right:30px;--awb-padding-bottom:100px;--awb-padding-left:30px;--awb-padding-top-medium:72px;--awb-padding-bottom-medium:72px;--awb-padding-top-small:48px;--awb-padding-bottom-small:48px;--awb-padding-left-small:30px;--awb-margin-top:0px;--awb-margin-bottom:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-stretch fusion-flex-content-wrap\" style=\"max-width:1144px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-4 fusion_builder_column_1_2 1_2 fusion-flex-column fusion-animated\" style=\"--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:3.84%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:3.84%;--awb-width-medium:60%;--awb-order-medium:0;--awb-margin-top-medium:2vw;--awb-spacing-right-medium:3.2%;--awb-margin-bottom-medium:2vw;--awb-spacing-left-medium:3.2%;--awb-width-small:100%;--awb-order-small:1;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-animationType=\"fadeInLeft\" data-animationDuration=\"1.3\" data-animationOffset=\"top-into-view\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-center fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-3 fusion-sep-none fusion-title-text fusion-title-size-one fusion-animated\" style=\"--awb-text-color:#000000;--awb-margin-top:10px;--awb-margin-bottom:30px;--awb-margin-top-small:10px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;--awb-sep-color:var(--awb-color3);\" data-animationType=\"fadeInRight\" data-animationDuration=\"1.2\" data-animationOffset=\"top-into-view\"><h1 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:48;line-height:1.4;\">Versatilidade e praticidade.<\/h1><\/div><div class=\"fusion-text fusion-text-3 fusion-text-no-margin\" style=\"--awb-font-size:22px;--awb-line-height:var(--awb-typography4-line-height);--awb-letter-spacing:var(--awb-typography4-letter-spacing);--awb-text-transform:var(--awb-typography4-text-transform);--awb-text-color:#000000;--awb-margin-right:15%;--awb-margin-bottom:45px;\"><p>Ideal para quem busca um viol\u00e3o para estudos, lazer e apresenta\u00e7\u00f5es. Um instrumento dur\u00e1vel e vers\u00e1til que acompanha o m\u00fasico em diferentes fases da jornada musical, oferecendo conforto e desempenho consistente em qualquer situa\u00e7\u00e3o.<\/p>\n<\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-5 fusion_builder_column_1_2 1_2 fusion-flex-column fusion-animated\" style=\"--awb-bg-position:center center;--awb-bg-blend:multiply;--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:13.44%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:3.84%;--awb-width-medium:40%;--awb-order-medium:0;--awb-spacing-right-medium:9.6%;--awb-spacing-left-medium:4.8%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-margin-bottom-small:40px;--awb-spacing-left-small:1.92%;\" data-animationType=\"fadeInRight\" data-animationDuration=\"1.3\" data-animationOffset=\"top-into-view\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-center fusion-content-layout-column\"><div class=\"fusion-image-element\" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-overlay-color:var(--awb-color1);--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-2 hover-type-none has-aspect-ratio\"><img decoding=\"async\" width=\"1200\" height=\"1200\" alt=\"lateral do viol\u00e3o nylon DH 69, DH 69T, roseta de viol\u00e3o\" title=\"DH69T-NT-violao-classico-EAGLE-Pro-Series-DH69T-NT-acabamento-natural-brilhante-detalhe3\" src=\"https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-NT-violao-classico-EAGLE-Pro-Series-DH69T-NT-acabamento-natural-brilhante-detalhe3-2.jpg\" class=\"img-responsive wp-image-27015 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" srcset=\"https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-NT-violao-classico-EAGLE-Pro-Series-DH69T-NT-acabamento-natural-brilhante-detalhe3-2-200x200.jpg 200w, https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-NT-violao-classico-EAGLE-Pro-Series-DH69T-NT-acabamento-natural-brilhante-detalhe3-2-400x400.jpg 400w, https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-NT-violao-classico-EAGLE-Pro-Series-DH69T-NT-acabamento-natural-brilhante-detalhe3-2-600x600.jpg 600w, https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-NT-violao-classico-EAGLE-Pro-Series-DH69T-NT-acabamento-natural-brilhante-detalhe3-2-800x800.jpg 800w, https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-NT-violao-classico-EAGLE-Pro-Series-DH69T-NT-acabamento-natural-brilhante-detalhe3-2.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, (max-width: 640px) 100vw, 600px\" \/><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-5 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--link_hover_color: var(--awb-color5);--link_color: var(--awb-color5);--awb-background-position:center bottom;--awb-border-sizes-top:0px;--awb-border-sizes-bottom:0px;--awb-border-sizes-left:0px;--awb-border-sizes-right:0px;--awb-border-color:var(--awb-color3);--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:100px;--awb-padding-right:30px;--awb-padding-bottom:100px;--awb-padding-left:30px;--awb-padding-top-medium:72px;--awb-padding-bottom-medium:72px;--awb-padding-top-small:48px;--awb-padding-bottom-small:48px;--awb-padding-left-small:30px;--awb-margin-top:0px;--awb-margin-bottom:0px;--awb-background-color:#ededed;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-stretch fusion-flex-content-wrap\" style=\"max-width:1144px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-6 fusion_builder_column_1_2 1_2 fusion-flex-column fusion-animated\" style=\"--awb-bg-position:center center;--awb-bg-blend:multiply;--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:13.44%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:3.84%;--awb-width-medium:40%;--awb-order-medium:0;--awb-spacing-right-medium:9.6%;--awb-spacing-left-medium:4.8%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-margin-bottom-small:40px;--awb-spacing-left-small:1.92%;\" data-animationType=\"fadeInRight\" data-animationDuration=\"1.3\" data-animationOffset=\"top-into-view\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-center fusion-content-layout-column\"><div class=\"fusion-image-element\" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-overlay-color:var(--awb-color1);--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-3 hover-type-none has-aspect-ratio\"><img decoding=\"async\" width=\"1200\" height=\"1200\" alt=\"equalizador Promix Eagle, pr\u00e9 amplificador Promix\" title=\"DH69T-NT-violao-classico-EAGLE-Pro-Series-DH69T-NT-acabamento-natural-brilhante-detalhe10\" src=\"https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-NT-violao-classico-EAGLE-Pro-Series-DH69T-NT-acabamento-natural-brilhante-detalhe10.jpg\" class=\"img-responsive wp-image-27010 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" srcset=\"https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-NT-violao-classico-EAGLE-Pro-Series-DH69T-NT-acabamento-natural-brilhante-detalhe10-200x200.jpg 200w, https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-NT-violao-classico-EAGLE-Pro-Series-DH69T-NT-acabamento-natural-brilhante-detalhe10-400x400.jpg 400w, https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-NT-violao-classico-EAGLE-Pro-Series-DH69T-NT-acabamento-natural-brilhante-detalhe10-600x600.jpg 600w, https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-NT-violao-classico-EAGLE-Pro-Series-DH69T-NT-acabamento-natural-brilhante-detalhe10-800x800.jpg 800w, https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-NT-violao-classico-EAGLE-Pro-Series-DH69T-NT-acabamento-natural-brilhante-detalhe10.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, (max-width: 640px) 100vw, 600px\" \/><\/span><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-7 fusion_builder_column_1_2 1_2 fusion-flex-column fusion-animated\" style=\"--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:3.84%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:3.84%;--awb-width-medium:60%;--awb-order-medium:0;--awb-margin-top-medium:2vw;--awb-spacing-right-medium:3.2%;--awb-margin-bottom-medium:2vw;--awb-spacing-left-medium:3.2%;--awb-width-small:100%;--awb-order-small:1;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-animationType=\"fadeInLeft\" data-animationDuration=\"1.3\" data-animationOffset=\"top-into-view\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-center fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-4 fusion-sep-none fusion-title-text fusion-title-size-one fusion-animated\" style=\"--awb-text-color:#000000;--awb-margin-top:10px;--awb-margin-bottom:30px;--awb-margin-top-small:10px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;--awb-sep-color:var(--awb-color3);\" data-animationType=\"fadeInRight\" data-animationDuration=\"1.2\" data-animationOffset=\"top-into-view\"><h1 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:48;line-height:1.4;\">O cl\u00e1ssico, agora plugado.<\/h1><\/div><div class=\"fusion-text fusion-text-4 fusion-text-no-margin\" style=\"--awb-font-size:22px;--awb-line-height:var(--awb-typography4-line-height);--awb-letter-spacing:var(--awb-typography4-letter-spacing);--awb-text-transform:var(--awb-typography4-text-transform);--awb-text-color:#000000;--awb-margin-right:15%;--awb-margin-bottom:45px;\"><p>Seguindo o mesmo padr\u00e3o de constru\u00e7\u00e3o do DH 69, um dos modelos de nylon mais vendidos da Eagle, o DH 69T recebe uma atualiza\u00e7\u00e3o importante: o pr\u00e9-amplificador Audisys Promix XR, com controles simples e de f\u00e1cil uso, garantindo precis\u00e3o, defini\u00e7\u00e3o e qualidade sonora para tocar com praticidade em qualquer lugar.<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-6 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--link_hover_color: var(--awb-color5);--link_color: var(--awb-color5);--awb-background-position:center bottom;--awb-border-sizes-top:0px;--awb-border-sizes-bottom:0px;--awb-border-sizes-left:0px;--awb-border-sizes-right:0px;--awb-border-color:var(--awb-color3);--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:100px;--awb-padding-right:30px;--awb-padding-bottom:100px;--awb-padding-left:30px;--awb-padding-top-medium:72px;--awb-padding-bottom-medium:72px;--awb-padding-top-small:48px;--awb-padding-bottom-small:48px;--awb-padding-left-small:30px;--awb-margin-top:0px;--awb-margin-bottom:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-stretch fusion-flex-content-wrap\" style=\"max-width:1144px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-8 fusion_builder_column_1_2 1_2 fusion-flex-column fusion-animated\" style=\"--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:3.84%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:3.84%;--awb-width-medium:60%;--awb-order-medium:0;--awb-margin-top-medium:2vw;--awb-spacing-right-medium:3.2%;--awb-margin-bottom-medium:2vw;--awb-spacing-left-medium:3.2%;--awb-width-small:100%;--awb-order-small:1;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-animationType=\"fadeInLeft\" data-animationDuration=\"1.3\" data-animationOffset=\"top-into-view\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-center fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-5 fusion-sep-none fusion-title-text fusion-title-size-one fusion-animated\" style=\"--awb-text-color:#000000;--awb-margin-top:10px;--awb-margin-bottom:30px;--awb-margin-top-small:10px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;--awb-sep-color:var(--awb-color3);\" data-animationType=\"fadeInRight\" data-animationDuration=\"1.2\" data-animationOffset=\"top-into-view\"><h1 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:48;line-height:1.4;\">Tradi\u00e7\u00e3o e qualidade.<\/h1><\/div><div class=\"fusion-text fusion-text-5 fusion-text-no-margin\" style=\"--awb-font-size:22px;--awb-line-height:var(--awb-typography4-line-height);--awb-letter-spacing:var(--awb-typography4-letter-spacing);--awb-text-transform:var(--awb-typography4-text-transform);--awb-text-color:#000000;--awb-margin-right:15%;--awb-margin-bottom:45px;\"><p>Os viol\u00f5es Eagle s\u00e3o refer\u00eancia, reconhecidos pela qualidade e durabilidade de constru\u00e7\u00e3o que atendem estudantes, professores e m\u00fasicos em todas as etapas da jornada musical. Escolher um Eagle \u00e9 investir em um instrumento confi\u00e1vel, bem constru\u00eddo e aprovado por quem entende de m\u00fasica.<\/p>\n<\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-9 fusion_builder_column_1_2 1_2 fusion-flex-column fusion-animated\" style=\"--awb-bg-position:center center;--awb-bg-blend:multiply;--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:13.44%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:3.84%;--awb-width-medium:40%;--awb-order-medium:0;--awb-spacing-right-medium:9.6%;--awb-spacing-left-medium:4.8%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-margin-bottom-small:40px;--awb-spacing-left-small:1.92%;\" data-animationType=\"fadeInRight\" data-animationDuration=\"1.3\" data-animationOffset=\"top-into-view\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-center fusion-content-layout-column\"><div class=\"fusion-image-element\" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-overlay-color:var(--awb-color1);--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-4 hover-type-none has-aspect-ratio\"><img decoding=\"async\" width=\"1200\" height=\"1200\" alt=\"costas do viol\u00e3o DH 69, fundo do viol\u00e3o DH 69T\" title=\"DH69T-NT-violao-classico-EAGLE-Pro-Series-DH69T-NT-acabamento-natural-brilhante-detalhe11\" src=\"https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-NT-violao-classico-EAGLE-Pro-Series-DH69T-NT-acabamento-natural-brilhante-detalhe11.jpg\" class=\"img-responsive wp-image-27021 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" srcset=\"https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-NT-violao-classico-EAGLE-Pro-Series-DH69T-NT-acabamento-natural-brilhante-detalhe11-200x200.jpg 200w, https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-NT-violao-classico-EAGLE-Pro-Series-DH69T-NT-acabamento-natural-brilhante-detalhe11-400x400.jpg 400w, https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-NT-violao-classico-EAGLE-Pro-Series-DH69T-NT-acabamento-natural-brilhante-detalhe11-600x600.jpg 600w, https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-NT-violao-classico-EAGLE-Pro-Series-DH69T-NT-acabamento-natural-brilhante-detalhe11-800x800.jpg 800w, https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-NT-violao-classico-EAGLE-Pro-Series-DH69T-NT-acabamento-natural-brilhante-detalhe11.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, (max-width: 640px) 100vw, 600px\" \/><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-7 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-background-color:#000000;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1144px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-10 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-padding-top:30px;--awb-padding-bottom:30px;--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"awb-gallery-wrapper awb-gallery-wrapper-2 button-span-no\"><div style=\"margin:-5px;--awb-bordersize:0px;\" class=\"fusion-gallery fusion-gallery-container fusion-grid-5 fusion-columns-total-5 fusion-gallery-layout-grid fusion-gallery-2\"><div style=\"padding:5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-5 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/eagle.com.br\/wp-content\/uploads\/bag-deluxe-detalhe-zipper-2.jpg\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_2]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/eagle.com.br\/wp-content\/uploads\/bag-deluxe-detalhe-zipper-2-320x202.jpg\" width=\"320\" height=\"202\" alt=\"ziper personalizado da bag acolchoada de violao eagle\" title=\"bag-deluxe-detalhe-zipper\" aria-label=\"bag-deluxe-detalhe-zipper\" class=\"img-responsive wp-image-30275 fusion-gallery-image-size-fixed\" srcset=\"https:\/\/eagle.com.br\/wp-content\/uploads\/bag-deluxe-detalhe-zipper-2-320x202.jpg 320w, https:\/\/eagle.com.br\/wp-content\/uploads\/bag-deluxe-detalhe-zipper-2-700x441.jpg 700w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/><\/a><\/div><\/div><div style=\"padding:5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-5 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/eagle.com.br\/wp-content\/uploads\/bag-deluxe-detalhe-tecido-interno-2.jpg\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_2]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/eagle.com.br\/wp-content\/uploads\/bag-deluxe-detalhe-tecido-interno-2-320x202.jpg\" width=\"320\" height=\"202\" alt=\"tecido interno da bag acolchoada de violao eagle\" title=\"bag-deluxe-detalhe-tecido-interno\" aria-label=\"bag-deluxe-detalhe-tecido-interno\" class=\"img-responsive wp-image-30276 fusion-gallery-image-size-fixed\" srcset=\"https:\/\/eagle.com.br\/wp-content\/uploads\/bag-deluxe-detalhe-tecido-interno-2-320x202.jpg 320w, https:\/\/eagle.com.br\/wp-content\/uploads\/bag-deluxe-detalhe-tecido-interno-2-700x441.jpg 700w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/><\/a><\/div><\/div><div class=\"clearfix\"><\/div><div style=\"padding:5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-5 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/eagle.com.br\/wp-content\/uploads\/bag-deluxe-detalhe-bordado-2.jpg\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_2]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/eagle.com.br\/wp-content\/uploads\/bag-deluxe-detalhe-bordado-2-320x202.jpg\" width=\"320\" height=\"202\" alt=\"logo bordado da bag acolchoada de violao eagle\" title=\"bag-deluxe-detalhe-bordado\" aria-label=\"bag-deluxe-detalhe-bordado\" class=\"img-responsive wp-image-30277 fusion-gallery-image-size-fixed\" srcset=\"https:\/\/eagle.com.br\/wp-content\/uploads\/bag-deluxe-detalhe-bordado-2-320x202.jpg 320w, https:\/\/eagle.com.br\/wp-content\/uploads\/bag-deluxe-detalhe-bordado-2-700x441.jpg 700w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/><\/a><\/div><\/div><div style=\"padding:5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-5 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/eagle.com.br\/wp-content\/uploads\/bag-deluxe-detalhe-apoios-de-borracha-2.jpg\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_2]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/eagle.com.br\/wp-content\/uploads\/bag-deluxe-detalhe-apoios-de-borracha-2-320x202.jpg\" width=\"320\" height=\"202\" alt=\"\" title=\"bag-deluxe-detalhe-apoios-de-borracha\" aria-label=\"bag-deluxe-detalhe-apoios-de-borracha\" class=\"img-responsive wp-image-30278 fusion-gallery-image-size-fixed\" srcset=\"https:\/\/eagle.com.br\/wp-content\/uploads\/bag-deluxe-detalhe-apoios-de-borracha-2-320x202.jpg 320w, https:\/\/eagle.com.br\/wp-content\/uploads\/bag-deluxe-detalhe-apoios-de-borracha-2-700x441.jpg 700w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/><\/a><\/div><\/div><div style=\"padding:5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-5 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/eagle.com.br\/wp-content\/uploads\/bag-deluxe-detalhe-alcas-1.jpg\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_2]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/eagle.com.br\/wp-content\/uploads\/bag-deluxe-detalhe-alcas-1-320x202.jpg\" width=\"320\" height=\"202\" alt=\"alcas da bag acolchoada de violao eagle\" title=\"bag-deluxe-detalhe-alcas\" aria-label=\"bag-deluxe-detalhe-alcas\" class=\"img-responsive wp-image-30279 fusion-gallery-image-size-fixed\" srcset=\"https:\/\/eagle.com.br\/wp-content\/uploads\/bag-deluxe-detalhe-alcas-1-320x202.jpg 320w, https:\/\/eagle.com.br\/wp-content\/uploads\/bag-deluxe-detalhe-alcas-1-700x441.jpg 700w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-8 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-11 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-margin-top:50px;--awb-margin-bottom:50px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-title title fusion-title-6 fusion-sep-none fusion-title-text fusion-title-size-three\" style=\"--awb-margin-top-small:0px;--awb-margin-right-small:0px;--awb-margin-bottom-small:20px;--awb-margin-left-small:0px;\"><h3 class=\"fusion-title-heading title-heading-left\" style=\"margin:0;\">Especifica\u00e7\u00f5es<\/h3><\/div>\n<div class=\"table-1\">\n<table width=\"100%\">\n<thead><\/thead>\n<tbody>\n<tr>\n<td align=\"left\"><strong>Tampo<\/strong><\/td>\n<td align=\"left\">Abeto (Spruce)<\/td>\n<\/tr>\n<tr>\n<td align=\"left\"><strong>Fundo<\/strong><\/td>\n<td align=\"left\">Mogno (Mahogany)<\/td>\n<\/tr>\n<tr>\n<td align=\"left\"><strong>Laterais<\/strong><\/td>\n<td align=\"left\">Mogno (Mahogany)<\/td>\n<\/tr>\n<tr>\n<td align=\"left\"><strong>Bra\u00e7o<\/strong><\/td>\n<td align=\"left\">Mogno Oriental (Nato)<\/td>\n<\/tr>\n<tr>\n<td align=\"left\"><strong>Escala<\/strong><\/td>\n<td align=\"left\">Laurel (Indian Laurel)<\/td>\n<\/tr>\n<tr>\n<td align=\"left\"><strong>Cavalete<\/strong><\/td>\n<td align=\"left\">Laurel (Indian Laurel)<\/td>\n<\/tr>\n<tr>\n<td align=\"left\"><strong>Roseta<\/strong><\/td>\n<td align=\"left\">Mosaico<\/td>\n<\/tr>\n<tr>\n<td align=\"left\"><strong>Filetes laterais<\/strong><\/td>\n<td align=\"left\">ABS<\/td>\n<\/tr>\n<tr>\n<td align=\"left\"><strong>Trastes<\/strong><\/td>\n<td align=\"left\">19 em Alpaca<\/td>\n<\/tr>\n<tr>\n<td align=\"left\"><strong>Tarraxas<\/strong><\/td>\n<td align=\"left\">Douradas<\/td>\n<\/tr>\n<tr>\n<td align=\"left\"><strong>Cordas<\/strong><\/td>\n<td align=\"left\">Tens\u00e3o m\u00e9dia<\/td>\n<\/tr>\n<tr>\n<td align=\"left\"><strong>Sistema de pr\u00e9-amplifica\u00e7\u00e3o<\/strong><\/td>\n<td align=\"left\">Audisys Promix XR<\/td>\n<\/tr>\n<tr>\n<td align=\"left\"><strong>Afinador<\/strong><\/td>\n<td align=\"left\">Crom\u00e1tico digital<\/td>\n<\/tr>\n<tr>\n<td align=\"left\"><strong>Acabamento<\/strong><\/td>\n<td align=\"left\">Verniz brilhante<\/td>\n<\/tr>\n<tr>\n<td align=\"left\"><strong>Nut<\/strong><\/td>\n<td align=\"left\">52 mm<\/td>\n<\/tr>\n<tr>\n<td align=\"left\"><strong>Comprimento da escala<\/strong><\/td>\n<td align=\"left\">650 mm \/ 25.5\u201d<\/td>\n<\/tr>\n<tr>\n<td align=\"left\"><strong>Acompanha<\/strong><\/td>\n<td align=\"left\">Bag Eagle Deluxe<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<div class=\"fusion-text fusion-text-6\" style=\"--awb-font-size:16px;--awb-margin-top:20px;\"><p><strong>Importante:<\/strong> Devido aos constantes aprimoramentos em nossa linha, o instrumento aqui demonstrado pode apresentar diferen\u00e7as visuais e\/ou de especifica\u00e7\u00f5es t\u00e9cnicas quando comparado \u00e0 vers\u00f5es anteriores que ainda estejam dispon\u00edveis no mercado ou expostas em <em>websites<\/em> de terceiros. <strong>Fotos e especifica\u00e7\u00f5es t\u00e9cnicas apresentadas nesta p\u00e1gina referem-se ao modelo mais recente.<\/strong><\/p>\n<\/div>\n<div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-bg-parallax\" data-bg-align=\"center center\" data-direction=\"down\" data-mute=\"false\" data-opacity=\"100\" data-velocity=\"-0.3\" data-mobile-enabled=\"false\" data-break_parents=\"0\" data-bg-image=\"https:\/\/eagle.com.br\/wp-content\/uploads\/promix-bg-1.jpg\" data-bg-repeat=\"false\" ><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-9 fusion-flex-container fusion-parallax-down nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-background-image:url(&quot;https:\/\/eagle.com.br\/wp-content\/uploads\/promix-bg-1.jpg&quot;);--awb-background-size:cover;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-justify-content-center fusion-flex-content-wrap\" style=\"max-width:1144px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-12 fusion_builder_column_1_2 1_2 fusion-flex-column fusion-no-small-visibility\" style=\"--awb-padding-top:75px;--awb-padding-bottom:75px;--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:3.84%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:4.416%;--awb-width-medium:33.333333333333%;--awb-order-medium:0;--awb-spacing-right-medium:5.76%;--awb-spacing-left-medium:6.624%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element\" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-5 hover-type-none\"><img decoding=\"async\" width=\"376\" height=\"158\" alt=\"logomarca Audisys Promix XR\" title=\"logomarca Audisys Promix XR\" src=\"https:\/\/eagle.com.br\/wp-content\/uploads\/logo-audisys-promix.png\" class=\"img-responsive wp-image-10528\" srcset=\"https:\/\/eagle.com.br\/wp-content\/uploads\/logo-audisys-promix-200x84.png 200w, https:\/\/eagle.com.br\/wp-content\/uploads\/logo-audisys-promix.png 376w\" sizes=\"(max-width: 1024px) 100vw, (max-width: 640px) 100vw, 376px\" \/><\/span><\/div><div class=\"fusion-text fusion-text-7\"><h4><span style=\"color: #ffffff;\">Exclusividade dos viol\u00f5es Eagle, o sistema de pr\u00e9-amplifica\u00e7\u00e3o Audisys \u2013 Promix XR proporciona timbres naturais com controles simples e intuitivos para voc\u00ea se concentrar no que mais importa: sua m\u00fasica!<\/span><\/h4>\n<p><span style=\"color: #ffffff;\">* Exceto modelo CH 800F<\/span><\/p>\n<\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-13 fusion_builder_column_1_2 1_2 fusion-flex-column fusion-no-small-visibility\" style=\"--awb-padding-top:75px;--awb-padding-bottom:64px;--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:3.84%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:3.84%;--awb-width-medium:33.333333333333%;--awb-order-medium:0;--awb-spacing-right-medium:5.76%;--awb-spacing-left-medium:5.76%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element\" style=\"text-align:right;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-6 hover-type-none\"><img decoding=\"async\" width=\"354\" height=\"490\" alt=\"Audisys Promix XR\" title=\"Promix XR\" src=\"https:\/\/eagle.com.br\/wp-content\/uploads\/promix-4.png\" class=\"img-responsive wp-image-10530\" srcset=\"https:\/\/eagle.com.br\/wp-content\/uploads\/promix-4-200x277.png 200w, https:\/\/eagle.com.br\/wp-content\/uploads\/promix-4.png 354w\" sizes=\"(max-width: 1024px) 100vw, (max-width: 640px) 100vw, 354px\" \/><\/span><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-14 fusion_builder_column_1_2 1_2 fusion-flex-column fusion-no-medium-visibility fusion-no-large-visibility\" style=\"--awb-padding-top:75px;--awb-padding-bottom:75px;--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:3.84%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:4.416%;--awb-width-medium:33.333333333333%;--awb-order-medium:0;--awb-spacing-right-medium:5.76%;--awb-spacing-left-medium:6.624%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element sm-text-align-center\" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-7 hover-type-none\"><img decoding=\"async\" width=\"376\" height=\"158\" alt=\"logomarca Audisys Promix XR\" title=\"logomarca Audisys Promix XR\" src=\"https:\/\/eagle.com.br\/wp-content\/uploads\/logo-audisys-promix.png\" class=\"img-responsive wp-image-10528\" srcset=\"https:\/\/eagle.com.br\/wp-content\/uploads\/logo-audisys-promix-200x84.png 200w, https:\/\/eagle.com.br\/wp-content\/uploads\/logo-audisys-promix.png 376w\" sizes=\"(max-width: 1024px) 100vw, (max-width: 640px) 100vw, 376px\" \/><\/span><\/div><div class=\"fusion-image-element sm-text-align-center\" style=\"text-align:right;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-8 hover-type-none\"><img decoding=\"async\" width=\"354\" height=\"490\" alt=\"Audisys Promix XR\" title=\"Promix XR\" src=\"https:\/\/eagle.com.br\/wp-content\/uploads\/promix-4.png\" class=\"img-responsive wp-image-10530\" srcset=\"https:\/\/eagle.com.br\/wp-content\/uploads\/promix-4-200x277.png 200w, https:\/\/eagle.com.br\/wp-content\/uploads\/promix-4.png 354w\" sizes=\"(max-width: 1024px) 100vw, (max-width: 640px) 100vw, 354px\" \/><\/span><\/div><div class=\"fusion-text fusion-text-8\"><h4><span style=\"color: #ffffff; font-size: 24px;\" data-fusion-font=\"true\">Exclusividade dos viol\u00f5es Eagle, o sistema de pr\u00e9-amplifica\u00e7\u00e3o Audisys \u2013 Promix XR proporciona timbres naturais com controles simples e intuitivos para voc\u00ea se concentrar no que mais importa: sua m\u00fasica!<\/span><\/h4>\n<p><span style=\"color: #ffffff;\">* Exceto modelo CH 800F<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div>\n<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-10 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:50px;--awb-padding-bottom:50px;--awb-margin-top:0px;--awb-margin-bottom:0px;--awb-background-color:#f2f2f2;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1144px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-15 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-7 fusion-sep-none fusion-title-text fusion-title-size-three\" style=\"--awb-margin-top-small:0px;--awb-margin-right-small:0px;--awb-margin-bottom-small:20px;--awb-margin-left-small:0px;\"><h3 class=\"fusion-title-heading title-heading-left\" style=\"margin:0;\">Perguntas frequentes<\/h3><\/div><style type=\"text\/css\">.fusion-faqs-wrapper #accordian-1 .fusion-panel { border-color:#e0dede; }.fusion-faqs-wrapper #accordian-1 .fusion-panel:hover{ border-color: #e0dede; }.fusion-accordian #accordian-1 .panel-title a .fa-fusion-box:before{ font-size: 13px;width: 13px;}.fusion-accordian #accordian-1 .panel-title a .fa-fusion-box{ color: #ffffff;}.fusion-accordian  #accordian-1 .panel-title a{font-family:\"Encode Sans Condensed\";font-style:normal;font-weight:400;}.fusion-accordian  #accordian-1 .panel-title a:not(:hover){}.fusion-accordian  #accordian-1 .toggle-content{font-family:\"Encode Sans Condensed\";font-style:normal;font-weight:300;}.fusion-accordian #accordian-1 .fa-fusion-box { background-color: #333333 !important;border-color: #333333 !important;}.fusion-accordian #accordian-1 .panel-title a:hover,.fusion-accordian #accordian-1 .panel-title a.hover { color: #ffbb00;}.fusion-faq-shortcode .fusion-accordian #accordian-1 .fusion-toggle-boxed-mode:hover .panel-title a { color: #ffbb00;}.fusion-accordian #accordian-1 .panel-title .active .fa-fusion-box,.fusion-accordian #accordian-1 .panel-title a:hover .fa-fusion-box,.fusion-accordian #accordian-1 .panel-title a.hover .fa-fusion-box { background-color: #ffbb00!important;border-color: #ffbb00!important;}<\/style><div class=\"fusion-faq-shortcode\" style=\"\"><div class=\"fusion-faqs-wrapper\"><div class=\"accordian fusion-accordian\"><div class=\"panel-group \" id=\"accordian-1\"><div class=\"fusion-panel fusion-toggle-no-divider panel-default fusion-faq-post fusion-faq-post-6704 geral \"><span class=\"entry-title rich-snippet-hidden\">Desejo saber o pre\u00e7o de um instrumento e fazer a encomenda. \u00c9 poss\u00edvel?<\/span><div class=\"panel-heading\"><h4 id=\"faq_1-6704\" class=\"panel-title toggle\"><a data-toggle=\"collapse\" class=\"collapsed\" data-parent=\"#accordian-1\" data-target=\"#collapse-1-6704\" href=\"#collapse-1-6704\" aria-expanded=\"false\"><div class=\"fusion-toggle-icon-wrapper\"><div class=\"fusion-toggle-icon-wrapper-main\"><div class=\"fusion-toggle-icon-wrapper-sub\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/div><\/div><\/div><div class=\"fusion-toggle-heading\">Desejo saber o pre\u00e7o de um instrumento e fazer a encomenda. \u00c9 poss\u00edvel?<\/div><\/a><\/h4><\/div><div id=\"collapse-1-6704\" aria-labelledby=\"faq_1-6704\" class=\"panel-collapse collapse\"><div class=\"panel-body toggle-content post-content\"><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-10-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-16 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-flex-grow-medium:;--awb-flex-shrink-medium:;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-flex-grow-small:;--awb-flex-shrink-small:;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-9\"><p>N\u00e3o fazemos venda direta ao consumidor e somente por nossa <a href=\"https:\/\/eagle.com.br\/onde-comprar\/\">rede de revendedores<\/a>. Por essa raz\u00e3o, n\u00e3o informamos pre\u00e7os finais, que dependem da pol\u00edtica comercial de cada lojista. Voc\u00ea encontrar\u00e1 nossos instrumentos nas principais lojas f\u00edsicas e <em>online<\/em> do pa\u00eds e nos principais <em>marketplaces<\/em>, como Mercado Livre, Americanas, Magalu entre outros.<\/p>\n<\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><div class=\"fusion-panel fusion-toggle-no-divider panel-default fusion-faq-post fusion-faq-post-6834 cordas violao \"><span class=\"entry-title rich-snippet-hidden\">Posso colocar cordas de n\u00e1ilon em um viol\u00e3o folk?<\/span><div class=\"panel-heading\"><h4 id=\"faq_1-6834\" class=\"panel-title toggle\"><a data-toggle=\"collapse\" class=\"collapsed\" data-parent=\"#accordian-1\" data-target=\"#collapse-1-6834\" href=\"#collapse-1-6834\" aria-expanded=\"false\"><div class=\"fusion-toggle-icon-wrapper\"><div class=\"fusion-toggle-icon-wrapper-main\"><div class=\"fusion-toggle-icon-wrapper-sub\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/div><\/div><\/div><div class=\"fusion-toggle-heading\">Posso colocar cordas de n\u00e1ilon em um viol\u00e3o folk?<\/div><\/a><\/h4><\/div><div id=\"collapse-1-6834\" aria-labelledby=\"faq_1-6834\" class=\"panel-collapse collapse\"><div class=\"panel-body toggle-content post-content\"><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-10-2 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-17 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-flex-grow-medium:;--awb-flex-shrink-medium:;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-flex-grow-small:;--awb-flex-shrink-small:;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-10\"><p>Viol\u00f5es cl\u00e1ssicos e viol\u00f5es folk s\u00e3o instrumentos distintos, com sua sonoridade caracter\u00edstica e cada um foi projetado e estruturado para receber o tipo correto de encordoamento. A altera\u00e7\u00e3o de encordoamento, embora possa ser feita nesse caso, ir\u00e1 alterar drasticamente o som do instrumento. Se voc\u00ea deseja fazer a altera\u00e7\u00e3o pois busca outra sonoridade sugerimos que voc\u00ea troque seu viol\u00e3o folk por um modelo cl\u00e1ssico.<\/p>\n<p>Se o problema \u00e9 algum desconforto ou dor nos dedos ao tocar um instrumento com cordas de a\u00e7o, saiba que isso \u00e9 normal para estudantes iniciantes no instrumento ou que n\u00e3o tocam com frequ\u00eancia e ainda n\u00e3o &#8220;calejaram&#8221; os dedos e essa \u00e9 uma quest\u00e3o comum para quem est\u00e1 iniciando e acredita que no viol\u00e3o cl\u00e1ssico &#8211; ou usando cordas de n\u00e1ilon &#8211; ser\u00e1 mais f\u00e1cil o aprendizado. Praticando com frequ\u00eancia, em pouco tempo voc\u00ea deixar\u00e1 de ter esse desconforto.<\/p>\n<p>Tamb\u00e9m \u00e9 poss\u00edvel que seu viol\u00e3o esteja desregulado ou com algum problema estrutural, fazendo com que as cordas fiquem distantes da escala do viol\u00e3o (popularmente conhecido como &#8220;empenamento&#8221;), o que exige maior for\u00e7a nos dedos e dificulta a execu\u00e7\u00e3o dos acordes. Nesse caso voc\u00ea deve procurar os servi\u00e7os de um t\u00e9cnico (luthier) que possa avaliar seu instrumento e fazer os ajustes necess\u00e1rios.<\/p>\n<p>Sugerimos tamb\u00e9m que voc\u00ea considere trocar o encordoamento de seu viol\u00e3o por um de tens\u00e3o mais leve.<\/p>\n<\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><div class=\"fusion-panel fusion-toggle-no-divider panel-default fusion-faq-post fusion-faq-post-2491 geral \"><span class=\"entry-title rich-snippet-hidden\">Como verificar a data da fabrica\u00e7\u00e3o do meu instrumento?<\/span><div class=\"panel-heading\"><h4 id=\"faq_1-2491\" class=\"panel-title toggle\"><a data-toggle=\"collapse\" class=\"collapsed\" data-parent=\"#accordian-1\" data-target=\"#collapse-1-2491\" href=\"#collapse-1-2491\" aria-expanded=\"false\"><div class=\"fusion-toggle-icon-wrapper\"><div class=\"fusion-toggle-icon-wrapper-main\"><div class=\"fusion-toggle-icon-wrapper-sub\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/div><\/div><\/div><div class=\"fusion-toggle-heading\">Como verificar a data da fabrica\u00e7\u00e3o do meu instrumento?<\/div><\/a><\/h4><\/div><div id=\"collapse-1-2491\" aria-labelledby=\"faq_1-2491\" class=\"panel-collapse collapse\"><div class=\"panel-body toggle-content post-content\"><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-10-3 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-18 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-11\"><p>Nossos n\u00fameros de s\u00e9rie seguem o seguinte padr\u00e3o, que permite identificar o ano de fabrica\u00e7\u00e3o do instrumento: XX(ano)XX(m\u00eas)XXXXX(n\u00famero em s\u00e9rie).<\/p>\n<p>Com o exemplo &#8220;130501222&#8221;, temos: maio\/13 &#8211; n\u00famero 01.222.<\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><div class=\"fusion-panel fusion-toggle-no-divider panel-default fusion-faq-post fusion-faq-post-2483 cordas violao \"><span class=\"entry-title rich-snippet-hidden\">Qual numera\u00e7\u00e3o ou tens\u00e3o de cordas devo usar no meu viol\u00e3o?<\/span><div class=\"panel-heading\"><h4 id=\"faq_1-2483\" class=\"panel-title toggle\"><a data-toggle=\"collapse\" class=\"collapsed\" data-parent=\"#accordian-1\" data-target=\"#collapse-1-2483\" href=\"#collapse-1-2483\" aria-expanded=\"false\"><div class=\"fusion-toggle-icon-wrapper\"><div class=\"fusion-toggle-icon-wrapper-main\"><div class=\"fusion-toggle-icon-wrapper-sub\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/div><\/div><\/div><div class=\"fusion-toggle-heading\">Qual numera\u00e7\u00e3o ou tens\u00e3o de cordas devo usar no meu viol\u00e3o?<\/div><\/a><\/h4><\/div><div id=\"collapse-1-2483\" aria-labelledby=\"faq_1-2483\" class=\"panel-collapse collapse\"><div class=\"panel-body toggle-content post-content\"><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-10-4 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-19 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-12\"><p>Essa \u00e9 uma quest\u00e3o subjetiva e depende do que cada m\u00fasico prioriza e da sua forma de tocar. Alguns m\u00fasicos preferem encordoamentos com tens\u00e3o mais pesada e que oferecem maior proje\u00e7\u00e3o sonora, mas que tamb\u00e9m exigem maior intensidade ao tocar, enquanto outros preferem encordoamentos mais leves. Um m\u00fasico de Flamenco tem necessidades diferentes de um m\u00fasico do Pop ou Bossa Nova. Existem ainda as diferen\u00e7as de material das cordas, que podem ser de n\u00e1ilon\/a\u00e7o, n\u00e1ilon\/bronze, com ou sem revestimento etc. Portanto, s\u00e3o muitas vari\u00e1veis para que se possa definir o que \u00e9 melhor para cada m\u00fasico. Sugerimos que voc\u00ea experimente diferentes encordoamentos at\u00e9 encontrar o que melhor se adapte \u00e0s suas necessidades e prefer\u00eancias.<\/p>\n<p>Nossos viol\u00f5es deixam a f\u00e1brica com encordoamento de tens\u00e3o m\u00e9dia\/leve, por se tratar de um &#8220;meio termo&#8221; entre as diferentes op\u00e7\u00f5es dispon\u00edveis no mercado, como forma de atender o maior n\u00famero de m\u00fasicos, lembrando que, em caso de altera\u00e7\u00e3o significativa na tens\u00e3o das cordas, talvez seja necess\u00e1rio fazer corre\u00e7\u00f5es no tensor do bra\u00e7o como forma de compensar a diferen\u00e7a na tens\u00e3o exercida pelas cordas.<\/p>\n<p>Tamb\u00e9m aconselhamos solicitar a avalia\u00e7\u00e3o de um t\u00e9cnico especializado (luthier), que possa avaliar seu instrumento, al\u00e9m de fazer revis\u00f5es peri\u00f3dicas para mant\u00ea-lo sempre em sua melhor condi\u00e7\u00e3o.<\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><div class=\"fusion-panel fusion-toggle-no-divider panel-default fusion-faq-post fusion-faq-post-2449 cordas violao \"><span class=\"entry-title rich-snippet-hidden\">Posso trocar o encordoamento de n\u00e1ilon do meu viol\u00e3o cl\u00e1ssico por cordas de a\u00e7o?<\/span><div class=\"panel-heading\"><h4 id=\"faq_1-2449\" class=\"panel-title toggle\"><a data-toggle=\"collapse\" class=\"collapsed\" data-parent=\"#accordian-1\" data-target=\"#collapse-1-2449\" href=\"#collapse-1-2449\" aria-expanded=\"false\"><div class=\"fusion-toggle-icon-wrapper\"><div class=\"fusion-toggle-icon-wrapper-main\"><div class=\"fusion-toggle-icon-wrapper-sub\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/div><\/div><\/div><div class=\"fusion-toggle-heading\">Posso trocar o encordoamento de n\u00e1ilon do meu viol\u00e3o cl\u00e1ssico por cordas de a\u00e7o?<\/div><\/a><\/h4><\/div><div id=\"collapse-1-2449\" aria-labelledby=\"faq_1-2449\" class=\"panel-collapse collapse\"><div class=\"panel-body toggle-content post-content\"><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-10-5 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-20 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-13\"><p>N\u00e3o. O viol\u00e3o de concep\u00e7\u00e3o cl\u00e1ssica deve utilizar somente encordoamentos apropriados para o modelo. A utiliza\u00e7\u00e3o de encordoamentos de a\u00e7o \u2013 destinados aos viol\u00f5es do tipo <em>folk<\/em> \u2013 pode acarretar s\u00e9rios danos estruturais ao viol\u00e3o, como empenamento do bra\u00e7o, rachaduras no corpo, descolamento do cavalete ou quebra do <em>headstock<\/em> (tamb\u00e9m conhecido como &#8220;m\u00e3o&#8221;), os quais n\u00e3o est\u00e3o preparados para suportar a tens\u00e3o elevada de encordoamentos de a\u00e7o. A utiliza\u00e7\u00e3o deste tipo de encordoamento resulta na perda autom\u00e1tica de qualquer garantia de f\u00e1brica.<\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><div class=\"fusion-panel fusion-toggle-no-divider panel-default fusion-faq-post fusion-faq-post-2480 baixo-eletroacustico guitarra-e-baixo cordas violao \"><span class=\"entry-title rich-snippet-hidden\">Quando devo trocar o encordoamento do meu instrumento?<\/span><div class=\"panel-heading\"><h4 id=\"faq_1-2480\" class=\"panel-title toggle\"><a data-toggle=\"collapse\" class=\"collapsed\" data-parent=\"#accordian-1\" data-target=\"#collapse-1-2480\" href=\"#collapse-1-2480\" aria-expanded=\"false\"><div class=\"fusion-toggle-icon-wrapper\"><div class=\"fusion-toggle-icon-wrapper-main\"><div class=\"fusion-toggle-icon-wrapper-sub\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/div><\/div><\/div><div class=\"fusion-toggle-heading\">Quando devo trocar o encordoamento do meu instrumento?<\/div><\/a><\/h4><\/div><div id=\"collapse-1-2480\" aria-labelledby=\"faq_1-2480\" class=\"panel-collapse collapse\"><div class=\"panel-body toggle-content post-content\"><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-10-6 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-21 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-14\"><p>A oxida\u00e7\u00e3o das cordas de a\u00e7o inicia-se a partir do momento em que s\u00e3o retiradas de sua embalagem original e instaladas no instrumento. Esse processo \u00e9 causado pela exposi\u00e7\u00e3o \u00e0 umidade do ar e acelerado pelo contato com a acidez presente no suor das m\u00e3os. A oxida\u00e7\u00e3o afeta as caracter\u00edsticas sonoras das cordas com perda sens\u00edvel da qualidade e dificultam a entona\u00e7\u00e3o (afina\u00e7\u00e3o) precisa do instrumento. Portanto, para um \u00f3timo desempenho \u00e9 aconselh\u00e1vel troc\u00e1-las periodicamente ou t\u00e3o logo apresentem pontos de oxida\u00e7\u00e3o (ferrugem).<\/p>\n<p>Para prolongar a vida \u00fatil de encordoamentos recomendamos que voc\u00ea fa\u00e7a a limpeza com pano seco sempre que terminar de utilizar o instrumento, mantendo-o longe de ambientes \u00famidos e de prefer\u00eancia guardado em estojo apropriado.<\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-11 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-22 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-padding-top:50px;--awb-bg-blend:overlay;--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-title title fusion-title-8 fusion-sep-none fusion-title-text fusion-title-size-three\" style=\"--awb-margin-top-small:0px;--awb-margin-right-small:0px;--awb-margin-bottom-small:20px;--awb-margin-left-small:0px;\"><h3 class=\"fusion-title-heading title-heading-left\" style=\"margin:0;\">Instrumentos Pro Series<strong><br \/>\n<\/strong><\/h3><\/div><div class=\"fusion-recent-posts fusion-recent-posts-1 avada-container layout-default layout-columns-5 fusion-recent-posts-center\"><section class=\"fusion-columns columns fusion-columns-5 columns-5\"><article class=\"post fusion-column column col-lg-2 col-md-2 col-sm-2\"><div class=\"fusion-flexslider fusion-flexslider-loading flexslider flexslider-hover-type-none\"><ul class=\"slides\"><li><a href=\"https:\/\/eagle.com.br\/en_us\/ch800f\/\" aria-label=\"CH 800F\" class=\"hover-type-none\"><img decoding=\"async\" width=\"600\" height=\"222\" src=\"https:\/\/eagle.com.br\/wp-content\/uploads\/CH800F-NT-violao-classico-eletroacustico-flat-EAGLE-Pro-Series-CH800F-NT-acabamento-natural-brilhante-lista.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/eagle.com.br\/wp-content\/uploads\/CH800F-NT-violao-classico-eletroacustico-flat-EAGLE-Pro-Series-CH800F-NT-acabamento-natural-brilhante-lista-200x74.jpg 200w, https:\/\/eagle.com.br\/wp-content\/uploads\/CH800F-NT-violao-classico-eletroacustico-flat-EAGLE-Pro-Series-CH800F-NT-acabamento-natural-brilhante-lista-400x148.jpg 400w, https:\/\/eagle.com.br\/wp-content\/uploads\/CH800F-NT-violao-classico-eletroacustico-flat-EAGLE-Pro-Series-CH800F-NT-acabamento-natural-brilhante-lista.jpg 600w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 928px) 196px, (min-width: 856px) 245px, (min-width: 784px) 327px, (min-width: 712px) 490px, (min-width: 640px) 712px, \" \/><\/a><\/li><\/ul><\/div><div class=\"recent-posts-content\"><h4 class=\"entry-title\"><a href=\"https:\/\/eagle.com.br\/en_us\/ch800f\/\">CH 800F<\/a><\/h4><p>Viol\u00e3o cl\u00e1ssico flat eletroac\u00fastico<\/p><\/div><\/article><article class=\"post fusion-column column col-lg-2 col-md-2 col-sm-2\"><div class=\"fusion-flexslider fusion-flexslider-loading flexslider flexslider-hover-type-none\"><ul class=\"slides\"><li><a href=\"https:\/\/eagle.com.br\/en_us\/ch800lh\/\" aria-label=\"CH 800 LH\" class=\"hover-type-none\"><img decoding=\"async\" width=\"600\" height=\"227\" src=\"https:\/\/eagle.com.br\/wp-content\/uploads\/CH800-LH-VG-violao-classico-eletroacustico-canhoto-EAGLE-Pro-Series-CH800-LH-VG-acabamento-vintage-brilhante-lista.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/eagle.com.br\/wp-content\/uploads\/CH800-LH-VG-violao-classico-eletroacustico-canhoto-EAGLE-Pro-Series-CH800-LH-VG-acabamento-vintage-brilhante-lista-200x76.jpg 200w, https:\/\/eagle.com.br\/wp-content\/uploads\/CH800-LH-VG-violao-classico-eletroacustico-canhoto-EAGLE-Pro-Series-CH800-LH-VG-acabamento-vintage-brilhante-lista-400x151.jpg 400w, https:\/\/eagle.com.br\/wp-content\/uploads\/CH800-LH-VG-violao-classico-eletroacustico-canhoto-EAGLE-Pro-Series-CH800-LH-VG-acabamento-vintage-brilhante-lista.jpg 600w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 928px) 196px, (min-width: 856px) 245px, (min-width: 784px) 327px, (min-width: 712px) 490px, (min-width: 640px) 712px, \" \/><\/a><\/li><\/ul><\/div><div class=\"recent-posts-content\"><h4 class=\"entry-title\"><a href=\"https:\/\/eagle.com.br\/en_us\/ch800lh\/\">CH 800 LH<\/a><\/h4><p>Viol\u00e3o cl\u00e1ssico canhoto<\/p><\/div><\/article><article class=\"post fusion-column column col-lg-2 col-md-2 col-sm-2\"><div class=\"fusion-flexslider fusion-flexslider-loading flexslider flexslider-hover-type-none\"><ul class=\"slides\"><li><a href=\"https:\/\/eagle.com.br\/en_us\/ch800\/\" aria-label=\"CH 800\" class=\"hover-type-none\"><img decoding=\"async\" width=\"600\" height=\"227\" src=\"https:\/\/eagle.com.br\/wp-content\/uploads\/CH800-VG-violao-classico-eletroacustico-EAGLE-Pro-Series-CH800-VG-acabamento-vintage-brilhante-lista.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/eagle.com.br\/wp-content\/uploads\/CH800-VG-violao-classico-eletroacustico-EAGLE-Pro-Series-CH800-VG-acabamento-vintage-brilhante-lista-200x76.jpg 200w, https:\/\/eagle.com.br\/wp-content\/uploads\/CH800-VG-violao-classico-eletroacustico-EAGLE-Pro-Series-CH800-VG-acabamento-vintage-brilhante-lista-400x151.jpg 400w, https:\/\/eagle.com.br\/wp-content\/uploads\/CH800-VG-violao-classico-eletroacustico-EAGLE-Pro-Series-CH800-VG-acabamento-vintage-brilhante-lista.jpg 600w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 928px) 196px, (min-width: 856px) 245px, (min-width: 784px) 327px, (min-width: 712px) 490px, (min-width: 640px) 712px, \" \/><\/a><\/li><\/ul><\/div><div class=\"recent-posts-content\"><h4 class=\"entry-title\"><a href=\"https:\/\/eagle.com.br\/en_us\/ch800\/\">CH 800<\/a><\/h4><p>Viol\u00e3o cl\u00e1ssico cutaway eletroac\u00fastico<\/p><\/div><\/article><article class=\"post fusion-column column col-lg-2 col-md-2 col-sm-2\"><div class=\"fusion-flexslider fusion-flexslider-loading flexslider flexslider-hover-type-none\"><ul class=\"slides\"><li><a href=\"https:\/\/eagle.com.br\/en_us\/dh69t\/\" aria-label=\"DH 69T\" class=\"hover-type-none\"><img decoding=\"async\" width=\"600\" height=\"224\" src=\"https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-VG-violao-classico-eletroacustico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-lista.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-VG-violao-classico-eletroacustico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-lista-200x75.jpg 200w, https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-VG-violao-classico-eletroacustico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-lista-400x149.jpg 400w, https:\/\/eagle.com.br\/wp-content\/uploads\/DH69T-VG-violao-classico-eletroacustico-EAGLE-Pro-Series-DH69T-VG-acabamento-vintage-brilhante-lista.jpg 600w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 928px) 196px, (min-width: 856px) 245px, (min-width: 784px) 327px, (min-width: 712px) 490px, (min-width: 640px) 712px, \" \/><\/a><\/li><\/ul><\/div><div class=\"recent-posts-content\"><h4 class=\"entry-title\"><a href=\"https:\/\/eagle.com.br\/en_us\/dh69t\/\">DH 69T<\/a><\/h4><p>Viol\u00e3o cl\u00e1ssico eletroac\u00fastico<\/p><\/div><\/article><article class=\"post fusion-column column col-lg-2 col-md-2 col-sm-2\"><div class=\"fusion-flexslider fusion-flexslider-loading flexslider flexslider-hover-type-none\"><ul class=\"slides\"><li><a href=\"https:\/\/eagle.com.br\/en_us\/dh69\/\" aria-label=\"DH 69\" class=\"hover-type-none\"><img decoding=\"async\" width=\"600\" height=\"225\" src=\"https:\/\/eagle.com.br\/wp-content\/uploads\/DH69-STNT-violao-classico-EAGLE-Pro-Series-DH69-STNT-acabamento-natural-acetinado-lista.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/eagle.com.br\/wp-content\/uploads\/DH69-STNT-violao-classico-EAGLE-Pro-Series-DH69-STNT-acabamento-natural-acetinado-lista-200x75.jpg 200w, https:\/\/eagle.com.br\/wp-content\/uploads\/DH69-STNT-violao-classico-EAGLE-Pro-Series-DH69-STNT-acabamento-natural-acetinado-lista-400x150.jpg 400w, https:\/\/eagle.com.br\/wp-content\/uploads\/DH69-STNT-violao-classico-EAGLE-Pro-Series-DH69-STNT-acabamento-natural-acetinado-lista.jpg 600w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 928px) 196px, (min-width: 856px) 245px, (min-width: 784px) 327px, (min-width: 712px) 490px, (min-width: 640px) 712px, \" \/><\/a><\/li><\/ul><\/div><div class=\"recent-posts-content\"><h4 class=\"entry-title\"><a href=\"https:\/\/eagle.com.br\/en_us\/dh69\/\">DH 69<\/a><\/h4><p>Viol\u00e3o cl\u00e1ssico<\/p><\/div><\/article><\/section><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Viol\u00e3o cl\u00e1ssico eletroac\u00fastico<\/p>","protected":false},"author":7,"featured_media":21292,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28,114,121],"tags":[],"class_list":["post-160","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eagle","category-violoes-classicos-eagle","category-violoes-classicos-eagle-pro-series"],"_links":{"self":[{"href":"https:\/\/eagle.com.br\/en_us\/wp-json\/wp\/v2\/posts\/160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eagle.com.br\/en_us\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eagle.com.br\/en_us\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eagle.com.br\/en_us\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/eagle.com.br\/en_us\/wp-json\/wp\/v2\/comments?post=160"}],"version-history":[{"count":1,"href":"https:\/\/eagle.com.br\/en_us\/wp-json\/wp\/v2\/posts\/160\/revisions"}],"predecessor-version":[{"id":33820,"href":"https:\/\/eagle.com.br\/en_us\/wp-json\/wp\/v2\/posts\/160\/revisions\/33820"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eagle.com.br\/en_us\/wp-json\/wp\/v2\/media\/21292"}],"wp:attachment":[{"href":"https:\/\/eagle.com.br\/en_us\/wp-json\/wp\/v2\/media?parent=160"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eagle.com.br\/en_us\/wp-json\/wp\/v2\/categories?post=160"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eagle.com.br\/en_us\/wp-json\/wp\/v2\/tags?post=160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}